{"id":32932,"date":"2025-06-11T08:19:10","date_gmt":"2025-06-11T08:19:10","guid":{"rendered":"http:\/\/18.196.36.165\/product\/pilot-hi-tecpoint-v5-0-5mm-1pc-4\/"},"modified":"2025-06-12T10:51:28","modified_gmt":"2025-06-12T10:51:28","slug":"pilot-hi-tecpoint-v5-0-5mm-1pc-4","status":"publish","type":"product","link":"https:\/\/www.tendeal.qa\/ar\/product\/pilot-hi-tecpoint-v5-0-5mm-1pc-4\/","title":{"rendered":"\u0628\u0627\u064a\u0644\u0648\u062a \u0647\u0627\u064a-\u062a\u0643 \u0628\u0648\u064a\u0646\u062a \u0641\u064a 5 - 0.5 \u0645\u0644\u0645 1 \u0642\u0637\u0639\u0629"},"content":{"rendered":"<p>\u0628\u0627\u064a\u0644\u0648\u062a \u0647\u0627\u064a-\u062a\u0643 \u0628\u0648\u064a\u0646\u062a \u0641\u064a 5 - 0.5 \u0645\u0644\u0645 1 \u0642\u0637\u0639\u0629<\/p>","protected":false},"excerpt":{"rendered":"<p>\u0628\u0627\u064a\u0644\u0648\u062a \u0647\u0627\u064a-\u062a\u0643 \u0628\u0648\u064a\u0646\u062a \u0641\u064a 5 - 0.5 \u0645\u0644\u0645 1 \u0642\u0637\u0639\u0629<\/p>","protected":false},"featured_media":34010,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"hs_code":""},"product_brand":[73],"product_cat":[1025],"product_tag":[4151,4152],"class_list":["post-32932","product","type-product","status-publish","has-post-thumbnail","product_brand-al-rawnaq","product_cat-other-office-school-supplies","product_tag-alrawnaq","product_tag-trading","first","instock","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.tendeal.qa\/ar\/wp-json\/wp\/v2\/product\/32932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tendeal.qa\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.tendeal.qa\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tendeal.qa\/ar\/wp-json\/wp\/v2\/comments?post=32932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tendeal.qa\/ar\/wp-json\/wp\/v2\/media\/34010"}],"wp:attachment":[{"href":"https:\/\/www.tendeal.qa\/ar\/wp-json\/wp\/v2\/media?parent=32932"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.tendeal.qa\/ar\/wp-json\/wp\/v2\/product_brand?post=32932"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.tendeal.qa\/ar\/wp-json\/wp\/v2\/product_cat?post=32932"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.tendeal.qa\/ar\/wp-json\/wp\/v2\/product_tag?post=32932"}],"curies":[{"name":"\u062f\u0628\u0644\u064a\u0648 \u0628\u064a","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}