{"id":16813,"date":"2025-05-27T12:04:05","date_gmt":"2025-05-27T12:04:05","guid":{"rendered":"http:\/\/18.196.36.165\/product\/haiifamajic-compact-powder-hnc-15\/"},"modified":"2025-05-27T13:45:37","modified_gmt":"2025-05-27T13:45:37","slug":"haiifamajic-compact-powder-hnc-15","status":"publish","type":"product","link":"https:\/\/www.tendeal.qa\/ar\/product\/haiifamajic-compact-powder-hnc-15\/","title":{"rendered":"\u0628\u0648\u062f\u0631\u0629 \u0647\u0627\u064a\u0641\u0627\u0645\u0627\u062c\u064a\u0643 \u0627\u0644\u0645\u062f\u0645\u062c\u0629 HNC 15"},"content":{"rendered":"<p>\u0647\u0627\u064a \u0641\u0627\u064a \u0645\u0627\u062c\u064a\u0643 \u0628\u0648\u062f\u0631\u0629 \u0645\u0636\u063a\u0648\u0637\u0629 HNC 15 \u062a\u063a\u0637\u064a\u0629 \u0643\u0627\u0645\u0644\u0629<\/p>","protected":false},"excerpt":{"rendered":"<p>\u0647\u0627\u064a \u0641\u0627\u064a \u0645\u0627\u062c\u064a\u0643 \u0628\u0648\u062f\u0631\u0629 \u0645\u0636\u063a\u0648\u0637\u0629 HNC 15 \u062a\u063a\u0637\u064a\u0629 \u0643\u0627\u0645\u0644\u0629<\/p>","protected":false},"featured_media":17147,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[92],"product_cat":[387],"product_tag":[2687],"class_list":{"0":"post-16813","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-beauty-touch","7":"product_cat-makeup","8":"product_tag-haiifamajic-compact-powder-hnc-15","10":"first","11":"instock","12":"purchasable","13":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.tendeal.qa\/ar\/wp-json\/wp\/v2\/product\/16813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tendeal.qa\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.tendeal.qa\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tendeal.qa\/ar\/wp-json\/wp\/v2\/comments?post=16813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tendeal.qa\/ar\/wp-json\/wp\/v2\/media\/17147"}],"wp:attachment":[{"href":"https:\/\/www.tendeal.qa\/ar\/wp-json\/wp\/v2\/media?parent=16813"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.tendeal.qa\/ar\/wp-json\/wp\/v2\/product_brand?post=16813"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.tendeal.qa\/ar\/wp-json\/wp\/v2\/product_cat?post=16813"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.tendeal.qa\/ar\/wp-json\/wp\/v2\/product_tag?post=16813"}],"curies":[{"name":"\u062f\u0628\u0644\u064a\u0648 \u0628\u064a","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}